{"id":409,"date":"2016-09-24T12:14:52","date_gmt":"2016-09-24T12:14:52","guid":{"rendered":"http:\/\/yukti.com.ar\/?p=409"},"modified":"2020-11-13T23:03:36","modified_gmt":"2020-11-13T23:03:36","slug":"como-hacer-microdosis-de-cannabis","status":"publish","type":"post","link":"https:\/\/yukti.com.ar\/index.php\/2016\/09\/24\/como-hacer-microdosis-de-cannabis\/","title":{"rendered":"\u00bfC\u00f3mo hacer microdosis de cannabis?"},"content":{"rendered":"<figure id=\"attachment_410\" aria-describedby=\"caption-attachment-410\" style=\"width: 150px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/yukti.com.ar\/wp-content\/uploads\/2016\/09\/cannabis_sativa.jpg\"><img loading=\"lazy\" class=\"wp-image-410 size-thumbnail\" src=\"http:\/\/yukti.com.ar\/wp-content\/uploads\/2016\/09\/cannabis_sativa-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><figcaption id=\"caption-attachment-410\" class=\"wp-caption-text\">cannabis<\/figcaption><\/figure>\n<p>Lo primero es contar con una planta<strong> \ud83d\ude42<\/strong> y la misma en proceso de floraci\u00f3n. Usamos la planta hembra de la cannabis, aunque con el macho tambi\u00e9n funciona. Usamos la totalidad de la planta, y reci\u00e9n colectada, para que preserve todas sus cualidades medicinales.<\/p>\n<p>Cortamos una \u201crama\u201d que contenga cogollo, hojas y tallos\u2026llenamos un frasco de vidrio, hasta arriba, con toda las partes de la planta: cogollo\/flor, ramas\/tallos, hojas\u2026 presionando suavemente&#8230; ac\u00e1 usamos frascos de vidrio, tipo el de mermeladas o m\u00e1s peque\u00f1o\u2026 se llena de planta el frasco y se le agrega alcohol et\u00edlico, (96% en Vol. uso medicinal), hasta cubrir toda la planta\u2026 se la tapa firmemente y se cubre el frasco con un papel que mantenga fuera de la luz el l\u00edquido.<\/p>\n<p>Etiquetamos el recipiente con nombre, fecha y alguna descripci\u00f3n de la planta, por ejemplo d\u00f3nde la colectamos.<\/p>\n<p><!--more-->Se lo agita diariamente (o cuando uno se acuerda)..<\/p>\n<p>A partir del s\u00e9ptimo d\u00eda la tintura en proceso ya est\u00e1 lista para ser colada. Si se la deja m\u00e1s tiempo, unos veinte d\u00edas, tambi\u00e9n est\u00e1 bien.<\/p>\n<p>Una vez colada y obtenida la <strong>Tintura<\/strong>, etiquetamos y volvemos a envolver el frasco, ahora de Tintura, con un papel que impida el paso de la luz.<\/p>\n<p><strong>Las Tinturas <\/strong>son t\u00f3xicas.<br \/>\nSi la conservamos en lugar fresco, oscuro y tranquilo duran muchos a\u00f1os.<\/p>\n<p>Para hacer la <strong>microdosis de cannabis<\/strong>, necesitamos ahora preparar aparte, el <strong>Veh\u00edculo<\/strong> sobre el que se va a diluir la Tintura.<\/p>\n<p>El <strong>Veh\u00edculo<\/strong> es una\u00a0soluci\u00f3n de alcohol y agua&#8230; una parte de alcohol de 96% y tres partes de agua (potable, si es de vertiente mejor)&#8230; es decir si vamos a preparar un litro de veh\u00edculo necesitamos 250 ml de alcohol y 750 ml de agua&#8230; Lo etiquetamos como <strong>Veh\u00edculo<\/strong>.<\/p>\n<p>Para obtener la microdosis de cannabis, ponemos en un frasco de vidrio de 20 ml (tipo gotero) 40 gotas (\u00f3 2 ml) de la Tintura de cannabis, y completamos el resto con el Veh\u00edculo.<\/p>\n<p>Es decir, en un gotero de vidrio de 20 ml ponemos 2 ml de Tintura de cannabis, y completamos con el Vehiculo&#8230; y obtenemos la <strong>microdosis de cannabis.<\/strong><\/p>\n<p><strong>Las propiedades de las microdosis son las propiedades de la planta<\/strong>, por lo que la microdosis de cannabis es eficiente para tratar epilepsias, convulsiones, parkinson, artrosis, artritis, fibromialgia, depresi\u00f3n, insomnio, trastornos alimentarios, el mal humor, el dolor. La cannabis relaja el sistema nervioso central.<\/p>\n<p><strong>Administraci\u00f3n de las microdosis:<\/strong><br \/>\nAl iniciar una toma:<br \/>\n-el primer d\u00eda (impregnacion): 2 gotas cada 2 horas, hasta la noche.<br \/>\n-los d\u00edas siguientes, 2 gotas, cuatro veces por d\u00eda.<\/p>\n<p>Toma de crisis: se pueden tomar dos gotas cada 10 minutos durante el lapso de una hora&#8230; el dolor va a desaparecer a la tercera o cuarta toma. Recuerde que las microdosis no tienen contraindicaciones.<\/p>\n<p>Si est\u00e0 tomando medicamentos farmace\u00f9ticos separar la toma de las microdosis unos 15 minutos. Las microdosis no tienen efectos nocivos sobre el organismo. Los remedios si.<\/p>\n<p>Para administrar m\u00e1s de una microdosis, es el mismo procedimiento, dos gotas en la punta de la lengua de cada uno de las microdosis, s\u00f3lo hay que dejar transcurrir un minuto o menos entre cada microdosis. Se pueden tomar cinco, seis o m\u00e1s microdosis, sin presentar ning\u00fan riesgo.<\/p>\n<p>Gracias! Abrazo circular<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo primero es contar con una planta \ud83d\ude42 y la misma en proceso de floraci\u00f3n. Usamos la planta hembra de la cannabis, aunque con el macho tambi\u00e9n funciona. Usamos la totalidad de la planta, y reci\u00e9n colectada, para que preserve todas sus cualidades medicinales. Cortamos una \u201crama\u201d que contenga cogollo, hojas y tallos\u2026llenamos un frasco [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"_links":{"self":[{"href":"https:\/\/yukti.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/409"}],"collection":[{"href":"https:\/\/yukti.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yukti.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yukti.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/yukti.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=409"}],"version-history":[{"count":5,"href":"https:\/\/yukti.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/409\/revisions"}],"predecessor-version":[{"id":543,"href":"https:\/\/yukti.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/409\/revisions\/543"}],"wp:attachment":[{"href":"https:\/\/yukti.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yukti.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yukti.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}